{"id":16606,"date":"2022-08-11T17:30:51","date_gmt":"2022-08-11T17:30:51","guid":{"rendered":"http:\/\/ancestrina.com\/come-il-rape-interviene-nella-mia-vita-quotidiana\/"},"modified":"2022-08-11T17:30:56","modified_gmt":"2022-08-11T17:30:56","slug":"come-il-rape-interviene-nella-mia-vita-quotidiana","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/","title":{"rendered":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1"},"content":{"rendered":"<h1>Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1<\/h1>\n<p>Abbiamo parlato molto di rap\u00e9 ultimamente ( <a href=\"https:\/\/ancestrina.com\/it\/cos-e-rape\/\">Cos'\u00e8 il rap\u00e9?<\/a> ), e sicuramente facendo ricerche troverete articoli che ne raccontano gli innumerevoli benefici. Oggi voglio raccontarvi cosa ho avuto quando <strong>ho scoperto la medicina e ho deciso di implementarla nel mio stile di vita<\/strong> . E quelli che potresti ottenere anche se vuoi davvero cambiare la tua giornata. Non posso dire che sia stato un cambiamento improvviso nella mia vita, il rapporto con la medicina \u00e8 avvenuto passo dopo passo, ci siamo conosciuti, siamo diventati amici, <strong>il che mi ha permesso di vedere il cambiamento nella mia prospettiva<\/strong> di vedere le circostanze che accadono in la mia vita. <strong>I movimenti dell'anima sono cos\u00ec, lentamente, passo dopo passo, senza impazienza<\/strong> . Penserei che tutti noi vogliamo cambiare il nostro stile di vita, ma non facciamo nulla per far s\u00ec che quel cambiamento avvenga davvero o aspettiamo un rimedio miracoloso, qualcosa che ci cambia magicamente senza dover fare un lavoro personale, oppure iniziamo perch\u00e9 qualcosa ci motiva, un discorso, un buon libro, qualsiasi cosa, facciamo un cambiamento sottile che dura a malapena i piccoli momenti di motivazione che potremmo avere all'inizio. Poi, l'effetto del quotidiano, dei fardelli, degli obblighi, della tua routine, ecc&#8230; Ci fanno tornare alla <strong>schiavit\u00f9 in cui siamo cos\u00ec abituati a non piacerci.<\/strong><\/p>\n<h3>In che modo il rap\u00e9 ci aiuta?<\/h3>\n<p><strong>Ci rende consapevoli degli atti inconsci che avvengono nella mente<\/strong> , ci permette di realizzare prima di reagire. Sfortunatamente, la stragrande maggioranza delle persone vive la nostra vita in automatico. Non viviamo davvero le nostre vite, la <strong>vita ci passa assorbiti nella nostra routine<\/strong> , nel nostro modo di essere, siamo come i morti viventi perch\u00e9 fin da piccoli siamo stati programmati per avere dei concetti che hanno determinato il nostro modo di essere, pensare e recitazione. <strong>La nostra storia personale determina il nostro presente<\/strong> , il passato programma la nostra mente e la condiziona ad agire in un certo modo in determinate circostanze. Il rap\u00e9 ti fa mettere in discussione ogni passo che fai, ogni pensiero che hai, ogni emozione che generi, ogni secondo che vivi, e cercare una ragione per quella situazione. <strong>Ti porta nelle profondit\u00e0 del tuo essere<\/strong>, ti mostra, ci sono ferite, giudizi, colpe e un'infinit\u00e0 di cose che portiamo e che decidiamo di seppellire per non vedere e anche se sentiamo che ci appesantiamo preferiamo non vedere, una volta che la medicina ce lo mostra , \u00e8 una nostra decisione cosa fare con questo, s\u00ec Non usciamo da quel programma mentale, non curiamo quella ferita, non ci liberiamo da quella colpa o ci liberiamo da quei giudizi, che abbiamo trincerati in questo momento, e ci lavoriamo&#8230; non saremo mai in grado di cambiare il nostro stile di vita.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"776\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri.jpg\" alt=\"rap\u00e9 tipo pixuri tabaco plantas milenarias\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri.jpg 780w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri-100x100.jpg 100w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri-600x597.jpg 600w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri-300x298.jpg 300w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri-150x150.jpg 150w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri-768x764.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h3>Come mai?<\/h3>\n<p>Perch\u00e9 continueremo a vedere le cose allo stesso modo, sotto lo stesso velo. <strong>La prospettiva che abbiamo imparato dall'infanzia e che ci fa giudicare, decidere e mettere in discussione ci\u00f2 che \u00e8 giusto o sbagliato<\/strong> , il buono dal cattivo, il bello dal brutto, il giusto dallo sbagliato. Se osserviamo, molte volte viviamo alla giornata <strong>senza renderci conto di cosa abbiamo fatto<\/strong> e perch\u00e9. Quante volte non ti sei reso conto fino a dopo aver reagito, di aver detto qualcosa di cui ti penti, di aver rimproverato duramente i tuoi figli, quante volte al giorno funzioniamo automaticamente, in quali situazioni ti disconnetti ed \u00e8 quello <strong>siamo totalmente inconsapevoli che questo \u00e8 il modo in cui andiamo nella nostra vita quotidiana<\/strong>.<\/p>\n<h3>E poi il rap\u00e9 cosa?<\/h3>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"779\" height=\"783\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu.jpg\" alt=\"rap\u00e9 tsunu ancestrina\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu.jpg 779w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu-100x100.jpg 100w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu-600x603.jpg 600w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu-298x300.jpg 298w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu-150x150.jpg 150w, https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/tsunu-768x772.jpg 768w\" sizes=\"(max-width: 779px) 100vw, 779px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p><strong>Il rap\u00e9 mette a tacere la nostra mente<\/strong>, con la mente in silenzio diventa possibile per noi separarci da essa, capiamo che non siamo la mente, e quando comprendiamo questo il suo controllo su di noi cede, <strong>facciamo in modo che tutto ci\u00f2 che accade passi attraverso i miei filtri<\/strong>, reagiamo sempre meno, c'\u00e8 sempre pi\u00f9 distanza tra pensiero e reazione, diventiamo capaci di fermarci prima di entrare in automatico.<\/p>\n<p><strong>Rap\u00e9 \u00e8 un viaggio verso il nostro interno<\/strong> , ci prende e ci mostra, ci indica e ci dice bene e cosa farai con questo, \u00e8 una nostra decisione se fare qualcosa o no, ma lo faremo in un modo consapevole.<\/p>\n<p>( <a href=\"https:\/\/ancestrina.com\/it\/il-rape-cambia-vita\/\">Il rap\u00e9 cambia la vita<\/a> )<\/p>\n<h3>E cosa ottengo con questo?<\/h3>\n<p>Il rap\u00e9 <strong>ci aiuta a raggiungere gli obiettivi che ci prefiggiamo,<\/strong> quello che fa \u00e8 svegliarci e permetterci di vedere il nostro interno. <strong>Ci aiuta a scoprire perch\u00e9 le cose accadono e come possiamo cambiarle<\/strong>, scoprendo da dove agiamo, oltre a definire chi siamo, perch\u00e9 abbiamo la vita che abbiamo e cosa dobbiamo fare per andare oltre. Personalmente, vedo lo spirito del rap\u00e9 come il personaggio dell'eremita dei tarocchi, quel vecchio saggio che punta la sua lanterna su di noi, sperando che ce ne accorgeremo. (<a href=\"https:\/\/ancestrina.com\/it\/benefici-rape\/\">benefici del rap\u00e9<\/a> )<\/p>\n<h3><a href=\"https:\/\/ancestrina.com\/el-rape-amazonas\/\">Qual \u00e8 stato il cambiamento nella mia vita?<\/a><\/h3>\n<p><strong>Fino a pochi anni fa ero solo un altro schiavo del sistema<\/strong>, una pecora che si limitava come tutte le altre a seguire la strada che mi era stata imposta, sentivo sempre che mi interrogava, mi sentivo un anarchico che andava contro quanto stabilito, senza capire che stavo facendo la stessa cosa che ho tanto criticato, ottenendo soldi per darmi la vita migliore che potevo, per me e per i miei figli. La mia vita \u00e8 diventata l'opposto di ci\u00f2 che avevo visto nei miei genitori, sono diventato per opposizione la stessa cosa che volevo disperatamente dimenticare. Il mio passato ha determinato il mio presente e mi ha reso uno di pi\u00f9. <strong>Avevo le mie attivit\u00e0, stavo andando molto bene, ma non riuscivo a sentirmi completo<\/strong> e mi limitavo a lavorare il pi\u00f9 possibile, ad essere sempre impegnato, pieno di impegni che mi rendevano stressato, arrabbiato, irrequieto, anche questo era quello che sapevo, Essendo cos\u00ec mi sentivo in un luogo familiare. E cos\u00ec avrei continuato fino alla vecchiaia, avendo vissuto una vita che non mi soddisfaceva e che non era quella che volevo davvero avere. <strong>Alcuni di noi hanno due tipi di vita, quella che viviamo e quella che vorremmo davvero vivere. <\/strong><\/p>\n<p>Vi invito, come me, a <strong>coinvolgervi maggiormente con questa medicina ancestrale<\/strong> , permettervi di scoprire e vivere nuove esperienze, ritrovare voi stessi e aprire le porte alle <strong>meraviglie del rap\u00e9<\/strong> .<\/p>\n<p style=\"text-align: center;\">Leggi <a href=\"https:\/\/ancestrina.com\/it\/come-interviene-il-rape-nella-mia-vita-quotidiana-parte-2\/\">qui<\/a> <strong>la seconda parte<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1 Abbiamo parlato molto di rap\u00e9 ultimamente ( Cos&#8217;\u00e8 il rap\u00e9? ), e sicuramente facendo ricerche troverete articoli che ne raccontano gli innumerevoli benefici. Oggi voglio raccontarvi cosa ho avuto quando ho scoperto la medicina e ho deciso di implementarla nel mio stile di vita . [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[542,577],"tags":[678,703,89,601,701,682,39,630,96,90,679,97,98,91,702,94,100,704,99,683],"class_list":["post-16606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","category-it-rape","tag-benefici-del-rape-it","tag-connessione-del-rape","tag-efectos-rape","tag-effetti-del-rape","tag-il-rape-nella-mia-vita","tag-il-tabacco-cambia","tag-medicina-ancestral","tag-medicina-antica","tag-rape-beneficios","tag-rape-cambios","tag-rape-come-medicina","tag-rape-como-medicina","tag-rape-conexion","tag-rape-en-mi-vida","tag-rape-la-medicina-antica","tag-rape-medicina-ancestral","tag-rape-para-estar-tranquilo","tag-rape-per-essere-calmo","tag-uso-del-rape","tag-uso-di-rape"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1 | Ancestrina<\/title>\n<meta name=\"description\" content=\"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1\" \/>\n<meta property=\"og:description\" content=\"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T17:30:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-11T17:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri.jpg\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1\",\"datePublished\":\"2022-08-11T17:30:51+00:00\",\"dateModified\":\"2022-08-11T17:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/\"},\"wordCount\":1039,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"keywords\":[\"benefici del rap\u00e9\",\"connessione del rap\u00e9\",\"Efectos rap\u00e9\",\"effetti del rap\u00e9\",\"il rap\u00e9 nella mia vita\",\"il tabacco cambia\",\"medicina ancestral\",\"medicina antica\",\"Rap\u00e9 beneficios\",\"Rap\u00e9 cambios\",\"Rap\u00e9 come medicina\",\"Rap\u00e9 como medicina\",\"Rap\u00e9 conexi\u00f3n\",\"Rap\u00e9 en mi vida\",\"Rap\u00e9 la medicina antica\",\"Rap\u00e9 medicina ancestral\",\"Rap\u00e9 para estar tranquilo\",\"rap\u00e9 per essere calmo\",\"Uso del rap\u00e9\",\"Uso di rap\u00e9\"],\"articleSection\":[\"Non categorizzato\",\"Rap\u00e9\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/\",\"name\":\"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1 | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"datePublished\":\"2022-08-11T17:30:51+00:00\",\"dateModified\":\"2022-08-11T17:30:56+00:00\",\"description\":\"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/come-il-rape-interviene-nella-mia-vita-quotidiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1 | Ancestrina","description":"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/","og_locale":"it_IT","og_type":"article","og_title":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1","og_description":"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9","og_url":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-08-11T17:30:51+00:00","article_modified_time":"2022-08-11T17:30:56+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/07\/pixuri.jpg","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Victor Silva","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1","datePublished":"2022-08-11T17:30:51+00:00","dateModified":"2022-08-11T17:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/"},"wordCount":1039,"publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","keywords":["benefici del rap\u00e9","connessione del rap\u00e9","Efectos rap\u00e9","effetti del rap\u00e9","il rap\u00e9 nella mia vita","il tabacco cambia","medicina ancestral","medicina antica","Rap\u00e9 beneficios","Rap\u00e9 cambios","Rap\u00e9 come medicina","Rap\u00e9 como medicina","Rap\u00e9 conexi\u00f3n","Rap\u00e9 en mi vida","Rap\u00e9 la medicina antica","Rap\u00e9 medicina ancestral","Rap\u00e9 para estar tranquilo","rap\u00e9 per essere calmo","Uso del rap\u00e9","Uso di rap\u00e9"],"articleSection":["Non categorizzato","Rap\u00e9"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/","url":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/","name":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1 | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","datePublished":"2022-08-11T17:30:51+00:00","dateModified":"2022-08-11T17:30:56+00:00","description":"Victor de Ancestrina ci racconta dalla sua esperienza personale come \u00e8 avvenuto il suo approccio alle medicine sacre e come funziona il rap\u00e9","breadcrumb":{"@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/it\/come-il-rape-interviene-nella-mia-vita-quotidiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Come interviene il rap\u00e9 nella mia vita quotidiana? Parte 1"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/it\/#website","url":"https:\/\/ancestrina.com\/it\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/it\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/16606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/comments?post=16606"}],"version-history":[{"count":0,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/16606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media\/35403"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media?parent=16606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/categories?post=16606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/tags?post=16606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}