{"id":16175,"date":"2022-08-10T22:49:12","date_gmt":"2022-08-10T22:49:12","guid":{"rendered":"http:\/\/ancestrina.com\/rape-samauma\/"},"modified":"2022-08-10T22:49:13","modified_gmt":"2022-08-10T22:49:13","slug":"rape-samauma","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/it\/rape-samauma\/","title":{"rendered":"Rap\u00e9 samauma"},"content":{"rendered":"<h1>Rap\u00e9 samauma<\/h1>\n<h2>essere pi\u00f9 empatico<\/h2>\n<p style=\"text-align: left;\"><strong>Essere in relazione con l'altro ci invita ad essere empatici.<\/strong> Quando siamo figli, genitori, coniugi, amici, studenti o insegnanti, ci troviamo di fronte al legame emotivo con un altro essere umano; e per mantenere sani quei legami dobbiamo rafforzare l'empatia e la compassione. Se hai difficolt\u00e0 a connetterti con la sensazione di metterti nei panni della persona che ami, o sei chiuso a quella disposizione di cuore aperto che attende e ascolta, sar\u00e0 difficile per te contattare i bisogni del tuo i propri cari per essere in equilibrio con le proprie esigenze.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/rape-anaua\/\"><em><strong>Rap\u00e9 Anaua<\/strong><\/em><\/a> )<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma.jpg\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma.jpg 800w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma-300x300.jpg 300w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma-150x150.jpg 150w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma-768x768.jpg 768w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma-600x600.jpg 600w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h3>S\u00ec&#8230;<\/h3>\n<ul>\n<li>Senti di prenderti in carico dei problemi degli altri. &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..Samauma<\/li>\n<li>Date senza ricevere o ricevete senza dare? &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;Samauma<\/li>\n<li>Pensi che sia difficile per te provare empatia? &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. &#8230;Samauma<\/li>\n<li>\u00c8 difficile per te mantenere legami emotivi sani e consolidati&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. &#8230;&#8230;&#8230;&#8230;&#8230;.. &#8230;&#8230;&#8230;&#8230;&#8230;..Samauma<\/li>\n<li>Hai la sensazione che il tuo cuore sia chiuso dall'ego e che tu voglia avere ragione&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.Samauma<\/li>\n<\/ul>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/rape-velandinho\/\"><em><strong>Rap\u00e9 Velandinho<\/strong><\/em><\/a> )<\/p>\n<p style=\"text-align: left;\"><strong><a href=\"https:\/\/ancestrina.com\/it\/producto\/rape-samauma\/\">Il rap\u00e9 Samauma<\/a> sar\u00e0 quella medicina che ti prender\u00e0 per mano per connetterti con la tua capacit\u00e0 di amare con empatia e compassione.<\/strong> Tutti noi abbiamo la capacit\u00e0 di esaltare l'amore universale che risiede nel nostro essere, ma per questo, dovrai spesso mettere a tacere la voce del S\u00e9 Egoico che ti porta a sperimentare l'orgoglio, l'eccessivo egoismo e il bisogno di avere il controllo sui tuoi legami . Essere in relazione \u00e8 saper unire due voci, o due bisogni, in modo armonioso ed equilibrato.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/rape-imburana\/\"><em><strong>Fiuto Imburana<\/strong><\/em><\/a> )<\/p>\n<p style=\"text-align: left;\"><strong>Quando apriamo il quarto chakra, che \u00e8 il chakra del cuore<\/strong> <strong>, sperimentiamo cosa significa amare incondizionatamente.<\/strong> Perdonare e mettersi al posto dei propri cari \u00e8 un esercizio quotidiano dove conta non solo la nostra verit\u00e0, ma anche la verit\u00e0 in comune. Essendo in una relazione di amore divino ed espansivo, sar\u00e0 importante mettere da parte quell'egoismo che non accetta altre forme oltre quelle che conosciamo. Cos\u00ec amare diventa esercizio di disporre l'anima a scoprire nuovi modi di essere, di vivere e di essere.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/rape-pimienta-longa\/\"><em><strong>Fiuto lungo al pepe<\/strong><\/em><\/a> )<\/p>\n<h3>Come si manifesta un quarto chakra equilibrato?<\/h3>\n<ul>\n<li>Empatia<\/li>\n<li>Compassione.<\/li>\n<li>Capacit\u00e0 di perdonare.<\/li>\n<li>Non ci sono allegati.<\/li>\n<li>Ama incondizionatamente, senza pretese, senza aspettarti nulla in cambio.<\/li>\n<li>Equilibrio emotivo.<\/li>\n<li>Guadagni aiutando o insegnando ad altre persone.<\/li>\n<\/ul>\n<h3>Come si manifesta un quarto chakra squilibrato?<\/h3>\n<ul>\n<li>Fai tuoi i problemi degli altri o preoccupati eccessivamente di loro.<\/li>\n<li>Mettere da parte i nostri bisogni per occuparci degli altri.<\/li>\n<li>Dare senza ricevere.<\/li>\n<li>Ricevere senza dare.<\/li>\n<li>Mancanza di empatia.<\/li>\n<li>Avere il controllo della coppia.<\/li>\n<li>Sensazione di solitudine, tristezza e malinconia.<\/li>\n<\/ul>\n<p style=\"text-align: center;\">Se vuoi saperne di pi\u00f9 su Rap\u00e9 Samauma, contattaci sui nostri social come <a style=\"color: #999999;\" href=\"https:\/\/www.instagram.com\/ancestrina\/\"><strong>@ancestrina<\/strong><\/a> , visita il nostro <a style=\"color: #999999;\" href=\"https:\/\/www.youtube.com\/c\/Ancestrina\/videos\"><strong>Canale YouTube<\/strong><\/a> o scrivici nei commenti per ricevere maggiori informazioni sul percorso della medicina. Sappiamo che <a style=\"color: #999999;\" href=\"https:\/\/ancestrina.com\/el-rape-cambia-vidas\/\"><strong>RAP\u00c9 CAMBIA LA VITA<\/strong><\/a> e <strong>ci piacerebbe che tu facessi parte di questa comunit\u00e0 che espande la coscienza attraverso le medicine ancestrali.<\/strong><\/p>\n<p style=\"text-align: center;\">Nello stesso modo, <strong>Se questo rap\u00e9 faceva parte del tuo percorso, condividi con noi le tue esperienze di guarigione e cambiamento nei commenti.<\/strong> Crediamo nelle storie di trasformazione che questa amorevole medicina ancestrale ha tramandato e siamo convinti che possa aiutare molti a tornare alla loro essenza, tornare al momento presente e vivere una vita piena di benessere e scopo.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Rap\u00e9 Samauma\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/47xIM4wWzcg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rap\u00e9 samauma essere pi\u00f9 empatico Essere in relazione con l&#8217;altro ci invita ad essere empatici. Quando siamo figli, genitori, coniugi, amici, studenti o insegnanti, ci troviamo di fronte al legame emotivo con un altro essere umano; e per mantenere sani quei legami dobbiamo rafforzare l&#8217;empatia e la compassione. Se hai difficolt\u00e0 a connetterti con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[542,577],"tags":[],"class_list":["post-16175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","category-it-rape"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rap\u00e9 samauma , empathy and compassion | Ancestrina<\/title>\n<meta name=\"description\" content=\"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/it\/rape-samauma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rap\u00e9 samauma\" \/>\n<meta property=\"og:description\" content=\"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/it\/rape-samauma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T22:49:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-10T22:49:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma.jpg\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"Rap\u00e9 samauma\",\"datePublished\":\"2022-08-10T22:49:12+00:00\",\"dateModified\":\"2022-08-10T22:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"articleSection\":[\"Non categorizzato\",\"Rap\u00e9\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/\",\"name\":\"Rap\u00e9 samauma , empathy and compassion | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"datePublished\":\"2022-08-10T22:49:12+00:00\",\"dateModified\":\"2022-08-10T22:49:13+00:00\",\"description\":\"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/rape-samauma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rap\u00e9 samauma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rap\u00e9 samauma , empathy and compassion | Ancestrina","description":"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/it\/rape-samauma\/","og_locale":"it_IT","og_type":"article","og_title":"Rap\u00e9 samauma","og_description":"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.","og_url":"https:\/\/ancestrina.com\/it\/rape-samauma\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-08-10T22:49:12+00:00","article_modified_time":"2022-08-10T22:49:13+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/samauma.jpg","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Victor Silva","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"Rap\u00e9 samauma","datePublished":"2022-08-10T22:49:12+00:00","dateModified":"2022-08-10T22:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","articleSection":["Non categorizzato","Rap\u00e9"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/it\/rape-samauma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/","url":"https:\/\/ancestrina.com\/it\/rape-samauma\/","name":"Rap\u00e9 samauma , empathy and compassion | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","datePublished":"2022-08-10T22:49:12+00:00","dateModified":"2022-08-10T22:49:13+00:00","description":"Rap\u00e9 Samauma, quando giudizio e autocritica sono i tuoi compagni inseparabili, con questo rap\u00e9 imparerai ad avere pi\u00f9 empatia e compassione con te stesso.","breadcrumb":{"@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/it\/rape-samauma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/it\/rape-samauma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Rap\u00e9 samauma"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/it\/#website","url":"https:\/\/ancestrina.com\/it\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/it\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/16175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/comments?post=16175"}],"version-history":[{"count":0,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/16175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media\/35403"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media?parent=16175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/categories?post=16175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/tags?post=16175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}