{"id":15857,"date":"2022-08-10T00:05:11","date_gmt":"2022-08-10T00:05:11","guid":{"rendered":"http:\/\/ancestrina.com\/conoscere-i-vantaggi-di-kambo\/"},"modified":"2022-10-27T16:03:54","modified_gmt":"2022-10-27T16:03:54","slug":"conoscere-i-vantaggi-di-kambo","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/","title":{"rendered":"CONOSCI I VANTAGGI DI KAMBO?"},"content":{"rendered":"<h1>CONOSCI I VANTAGGI DI KAMBO?<\/h1>\n<p><strong>Il Kambo \u00e8 una medicina che pu\u00f2 essere considerata complessa e, soprattutto, controversa.<\/strong> \u00c8 stato aperto il dibattito sul fatto che si tratti di veleno o medicina, oppure sono state sollevate domande su come il &#8220;veleno&#8221; di una rana possa portare benefici. La verit\u00e0 \u00e8 che questa \u00e8 stata una pratica medicinale praticata dalle comunit\u00e0 indigene per migliaia di anni, oltre a far parte della conoscenza ancestrale che hanno salvaguardato per sostenere la salute e l'equilibrio della trib\u00f9. Ecco perch\u00e9 oggi parleremo del Kambo e vi parleremo anche di alcuni dei benefici di cui hanno approfittato le comunit\u00e0 ancestrali quando hanno utilizzato questo medicinale per s\u00e9 e per tutti coloro che hanno ricevuto il richiamo della rana che purifica e purifica.<\/p>\n<p style=\"text-align: center;\"><a style=\"color: #000000;\" href=\"https:\/\/ancestrina.com\/it\/qual-e-il-significato-dello-sciamanesimo\/\"><em><strong>(QUAL \u00c8 IL SIGNIFICATO DELLO SCIAMANISMO?)<\/strong><\/em><\/a><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"534\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno.jpeg\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno.jpeg 900w, https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno-300x178.jpeg 300w, https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno-768x456.jpeg 768w, https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno-600x356.jpeg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h2>COS'\u00c8 KAMBO?<\/h2>\n<p>Il Kamb\u00f3 \u00e8 una delle medicine ancestrali che ha protetto il territorio amazzonico per i suoi benefici per la salute integrale dell'essere. Consiste nell'utilizzo del \u201cveleno\u201d di una rana del territorio denominata <em>Phyllomedusa Bicolor<\/em> per scopi curativi e medicinali. Per estrarre questa sostanza, le comunit\u00e0 ancestrali dell'Amazzonia hanno creato un modo sicuro e compassionevole con la rana perch\u00e9 \u00e8 l'essere che fornisce la medicina. Sebbene possa essere considerata una pratica poco saggia, le comunit\u00e0 indigene hanno insistito sulla pratica del Kambo per i suoi molteplici benefici per l'equilibrio di corpo, mente e spirito.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/it\/la-rape-come-rituale-per-riconnettersi-con-la-propria-essenza\/\"><em><strong>(RAP\u00c9 COME RITUALE PER CONNETTERSI CON LA TUA ESSENZA)<\/strong><\/em><\/a><\/p>\n<h2>QUALI SONO I VANTAGGI DI KAMBO?<\/h2>\n<ul>\n<li>Parte dei vantaggi di Kambo \u00e8 che ha una potente azione sul sistema immunitario. Puoi attivarlo e, allo stesso tempo, rafforzarlo.<\/li>\n<li>Il Kamb\u00f3 \u00e8 stato utilizzato per accompagnare i trattamenti per la dipendenza, uno dei suoi vantaggi \u00e8 ridurre o eliminare il fumo, l'alcolismo e la dipendenza da altre droghe.<\/li>\n<li>Un altro dei suoi vantaggi \u00e8 che si \u00e8 rivelato essere un medicinale che stimola i sistemi del corpo fisico come il sistema circolatorio e il sistema nervoso centrale.<\/li>\n<li>\u00c8 stato confermato che un altro dei vantaggi di Kambo \u00e8 che ha una potente azione analgesica.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/it\/come-lo-sciamanesimo-usa-il-potere-animali\/\"><em><strong>(COME LO SCIAMANISMO UTILIZZA GLI ANIMALI DEL POTERE?)<\/strong><\/em><\/a><\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Mi experiencias con las comunidades ind\u00edgenas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9Hyf65KirgU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CONOSCI I VANTAGGI DI KAMBO? Il Kambo \u00e8 una medicina che pu\u00f2 essere considerata complessa e, soprattutto, controversa. \u00c8 stato aperto il dibattito sul fatto che si tratti di veleno o medicina, oppure sono state sollevate domande su come il &#8220;veleno&#8221; di una rana possa portare benefici. La verit\u00e0 \u00e8 che questa \u00e8 stata una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[582],"tags":[],"class_list":["post-15857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kambo-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CONOSCI I VANTAGGI DI KAMBO? | Ancestrina<\/title>\n<meta name=\"description\" content=\"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONOSCI I VANTAGGI DI KAMBO?\" \/>\n<meta property=\"og:description\" content=\"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T00:05:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T16:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno.jpeg\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"CONOSCI I VANTAGGI DI KAMBO?\",\"datePublished\":\"2022-08-10T00:05:11+00:00\",\"dateModified\":\"2022-10-27T16:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/kambo-2.webp\",\"articleSection\":[\"Kambo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/\",\"name\":\"CONOSCI I VANTAGGI DI KAMBO? | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/kambo-2.webp\",\"datePublished\":\"2022-08-10T00:05:11+00:00\",\"dateModified\":\"2022-10-27T16:03:54+00:00\",\"description\":\"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/kambo-2.webp\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/kambo-2.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/conoscere-i-vantaggi-di-kambo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONOSCI I VANTAGGI DI KAMBO?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/it\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CONOSCI I VANTAGGI DI KAMBO? | Ancestrina","description":"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/","og_locale":"it_IT","og_type":"article","og_title":"CONOSCI I VANTAGGI DI KAMBO?","og_description":"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?","og_url":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-08-10T00:05:11+00:00","article_modified_time":"2022-10-27T16:03:54+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/05\/bufo-alvarius-foto-uno.jpeg","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Victor Silva","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"CONOSCI I VANTAGGI DI KAMBO?","datePublished":"2022-08-10T00:05:11+00:00","dateModified":"2022-10-27T16:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/kambo-2.webp","articleSection":["Kambo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/","url":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/","name":"CONOSCI I VANTAGGI DI KAMBO? | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/kambo-2.webp","datePublished":"2022-08-10T00:05:11+00:00","dateModified":"2022-10-27T16:03:54+00:00","description":"Il Kambo \u00e8 una medicina antica che pu\u00f2 essere considerata complessa e, soprattutto, controversa. Conosci gi\u00e0 i suoi vantaggi?","breadcrumb":{"@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/kambo-2.webp","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/kambo-2.webp","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/it\/conoscere-i-vantaggi-di-kambo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"CONOSCI I VANTAGGI DI KAMBO?"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/it\/#website","url":"https:\/\/ancestrina.com\/it\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/it\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/it\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/15857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/comments?post=15857"}],"version-history":[{"count":1,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/15857\/revisions"}],"predecessor-version":[{"id":22774,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/posts\/15857\/revisions\/22774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media\/32171"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/media?parent=15857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/categories?post=15857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/it\/wp-json\/wp\/v2\/tags?post=15857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}