{"id":22138,"date":"2022-10-06T17:03:10","date_gmt":"2022-10-06T17:03:10","guid":{"rendered":"http:\/\/ancestrina.com\/quest-ce-que-la-depression\/"},"modified":"2022-10-26T23:26:52","modified_gmt":"2022-10-26T23:26:52","slug":"quest-ce-que-la-depression","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/","title":{"rendered":"Qu&rsquo;est-ce que la d\u00e9pression ?"},"content":{"rendered":"<h1>Qu&rsquo;est-ce que la d\u00e9pression ?<\/h1>\n<p>Avec la vie, il y a la souffrance sous forme de maladie. Nous pensons que ce sont les microbes, les virus, les bact\u00e9ries et les blessures qui causent des maladies dans notre corps physique. De m\u00eame, nous pensons que c&rsquo;est principalement un d\u00e9s\u00e9quilibre de la chimie du cerveau qui cause les maladies mentales et \u00e9motionnelles, telles que la d\u00e9pression, la d\u00e9pendance, etc.<\/p>\n<p>Dans le chamanisme, en revanche, ces maladies et affections sont per\u00e7ues comme des effets. On pense que pour une v\u00e9ritable gu\u00e9rison, on ne peut pas simplement masquer et supprimer ces effets, ou sympt\u00f4mes, avec des m\u00e9dicaments; nous devons nous attaquer \u00e0 la cause profonde de tous ces probl\u00e8mes. La cause profonde va bien au-del\u00e0 des virus, des bact\u00e9ries et de la chimie du cerveau&nbsp;; la cause principale vient du domaine int\u00e9rieur, et non physique.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/fr\/quest-ce-que-lanxiete\/\"><em><strong>(QU&rsquo;EST-CE QUE L&rsquo;ANXI\u00c9T\u00c9&nbsp;?)<\/strong><\/em><\/a><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"246\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp 420w, https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1-300x176.webp 300w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h2>Les 3 causes de la d\u00e9pression<\/h2>\n<p>D&rsquo;un point de vue chamanique, il existe 3 causes classiques de d\u00e9pression :<\/p>\n<h3>disharmonie (ou perte de puissance)<\/h3>\n<p>La discorde, ou la perte de pouvoir personnel, survient souvent lorsqu&rsquo;une personne a perdu un lien important avec la vie ou lorsque la vie semble perdre son sens. Cela peut se produire de mani\u00e8re subtile ou catastrophique ; de toute fa\u00e7on, nous subissons une perte de subsistance et de sens, et subissons une perte de pouvoir dans le processus. <\/p>\n<p>Cette perte de volont\u00e9, ou de puissance vitale, affecte fortement et directement notre matrice \u00e9nerg\u00e9tique et peut nous rendre tr\u00e8s vuln\u00e9rables aux maladies. Un exemple courant mais tragique de cela est lorsqu&rsquo;un couple de personnes \u00e2g\u00e9es a pass\u00e9 la majeure partie de sa vie ensemble et que l&rsquo;un d&rsquo;eux d\u00e9c\u00e8de. Le survivant entre souvent dans une crise de la vie apr\u00e8s la perte et peu de temps apr\u00e8s, d\u00e9veloppe une d\u00e9pression puis meurt. C&rsquo;est une cause de disharmonie due \u00e0 la perte d&rsquo;un \u00eatre cher.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/fr\/quest-ce-que-linsomnie\/\"><em><strong>(QU&rsquo;EST-CE QUE L&rsquo;INSOMNIE&nbsp;?)<\/strong><\/em><\/a><\/p>\n<h3>Craindre<\/h3>\n<p>La peur est la cause la plus fr\u00e9quente de d\u00e9pression. La peur est responsable des \u00e9motions qui am\u00e8nent votre corps \u00e0 entrer dans un \u00e9tat de stress puis de d\u00e9pression. <\/p>\n<p>Les scientifiques et les chercheurs s&rsquo;accordent \u00e9galement \u00e0 dire que lorsque ces hormones productrices de stress sont pr\u00e9sentes, elles commencent rapidement \u00e0 d\u00e9sint\u00e9grer le manteau protecteur du syst\u00e8me immunitaire de l&rsquo;organisme, ainsi que la matrice \u00e9nerg\u00e9tique globale. La maladie de la d\u00e9pression, par cons\u00e9quent, est in\u00e9vitable.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/fr\/quels-sont-les-animaux-de-pouvoir\/\"><strong><em>(QUE SONT LES ANIMAUX DE POUVOIR&nbsp;?)<\/em><\/strong><\/a><\/p>\n<h3>perte d&rsquo;\u00e2me<\/h3>\n<p>La perte d&rsquo;\u00e2me est la cause la plus extr\u00eame, bien que malheureusement encore courante, de la d\u00e9pression ; en fait, c&rsquo;est le diagnostic le plus grave et l&rsquo;une des principales causes de maladie grave et m\u00eame de d\u00e9c\u00e8s pr\u00e9matur\u00e9.<\/p>\n<p>La perte d&rsquo;\u00e2me survient le plus souvent apr\u00e8s une exp\u00e9rience traumatisante, comme se battre dans une guerre (un d\u00e9clencheur trop courant du SSPT), un divorce amer ou une intimidation intense. Dans certains cas, ces exp\u00e9riences peuvent \u00eatre si d\u00e9vastatrices que l&rsquo;\u00e2me peut commencer \u00e0 se fragmenter et \u00e0 se dissocier. Dans les cas les plus extr\u00eames et accablants, ces parties de l&rsquo;\u00e2me sont trop perdues et ne reviennent pas.<\/p>\n<p>Nous avons entendu des gens dire des choses comme \u00ab&nbsp;Je ne suis plus le m\u00eame depuis l&rsquo;incident&nbsp;\u00bb ou \u00ab&nbsp;Une partie de moi est morte ce jour-l\u00e0&nbsp;\u00bb. Ces commentaires sont des signes avant-coureurs d&rsquo;une perte d&rsquo;\u00e2me.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/fr\/a-quoi-servent-les-animaux-de-pouvoir-dans-le-chamanisme\/\"><em><strong>(\u00c0 QUOI SONT LES ANIMAUX DE POUVOIR UTILIS\u00c9S DANS LE CHAMANISME&nbsp;?)<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce que la d\u00e9pression ? Avec la vie, il y a la souffrance sous forme de maladie. Nous pensons que ce sont les microbes, les virus, les bact\u00e9ries et les blessures qui causent des maladies dans notre corps physique. De m\u00eame, nous pensons que c&rsquo;est principalement un d\u00e9s\u00e9quilibre de la chimie du cerveau qui cause [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[750,746],"tags":[],"class_list":["post-22138","post","type-post","status-publish","format-standard","hentry","category-insomnie","category-sante-mentale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qu&#039;est-ce que la d\u00e9pression ? | Ancestrina<\/title>\n<meta name=\"description\" content=\"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est-ce que la d\u00e9pression ?\" \/>\n<meta property=\"og:description\" content=\"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T17:03:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T23:26:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"Qu&rsquo;est-ce que la d\u00e9pression ?\",\"datePublished\":\"2022-10-06T17:03:10+00:00\",\"dateModified\":\"2022-10-26T23:26:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/\"},\"wordCount\":636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"articleSection\":[\"insomnie\",\"Sant\u00e9 mentale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/\",\"name\":\"Qu'est-ce que la d\u00e9pression ? | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"datePublished\":\"2022-10-06T17:03:10+00:00\",\"dateModified\":\"2022-10-26T23:26:52+00:00\",\"description\":\"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/quest-ce-que-la-depression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/domicile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&#8217;est-ce que la d\u00e9pression ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/fr\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qu'est-ce que la d\u00e9pression ? | Ancestrina","description":"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu'est-ce que la d\u00e9pression ?","og_description":"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.","og_url":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-10-06T17:03:10+00:00","article_modified_time":"2022-10-26T23:26:52+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Victor Silva","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/fr\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"Qu&rsquo;est-ce que la d\u00e9pression ?","datePublished":"2022-10-06T17:03:10+00:00","dateModified":"2022-10-26T23:26:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/fr\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","articleSection":["insomnie","Sant\u00e9 mentale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/","url":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/","name":"Qu'est-ce que la d\u00e9pression ? | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","datePublished":"2022-10-06T17:03:10+00:00","dateModified":"2022-10-26T23:26:52+00:00","description":"La cause profonde de la d\u00e9pression va bien au-del\u00e0 de la chimie du cerveau ; la cause principale vient du domaine int\u00e9rieur, et non physique.","breadcrumb":{"@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/fr\/quest-ce-que-la-depression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/fr\/domicile\/"},{"@type":"ListItem","position":2,"name":"Qu&#8217;est-ce que la d\u00e9pression ?"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/fr\/#website","url":"https:\/\/ancestrina.com\/fr\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/fr\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ancestrina.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/fr\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/posts\/22138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/comments?post=22138"}],"version-history":[{"count":2,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/posts\/22138\/revisions"}],"predecessor-version":[{"id":22552,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/posts\/22138\/revisions\/22552"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/media?parent=22138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/categories?post=22138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/fr\/wp-json\/wp\/v2\/tags?post=22138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}