{"id":8404,"date":"2022-01-21T16:50:22","date_gmt":"2022-01-21T16:50:22","guid":{"rendered":"http:\/\/ancestrina.com\/rape-imburana-zur-behandlung-allergien\/"},"modified":"2022-08-04T12:58:05","modified_gmt":"2022-08-04T12:58:05","slug":"rape-imburana","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/de\/rape-imburana\/","title":{"rendered":"RAP\u00c9 IMBURANA"},"content":{"rendered":"<h1>RAP\u00c9 IMBURANA<\/h1>\n<h2>Zur Behandlung von Allergien<\/h2>\n<p style=\"text-align: left;\">Wenn Sie normalerweise an allergischen Erkrankungen wie Asthma, Allergien, Rhinitis, Rosacea oder Ekzemen leiden, hilft es Ihnen nicht nur, Medikamente zu haben, die Ihnen helfen, die Symptome zu lindern &#8230; Aber gehen Sie viel tiefer. Im Allgemeinen <strong>haben Allergien aus einem emotionalen und subtilen Bereich mit jenen Elementen oder Erfahrungen zu tun, die wir aus dem Leben ablehnen.<\/strong> Pl\u00f6tzlich werden wir gegen\u00fcber bestimmten Szenarien \u201eintolerant\u201c, und der K\u00f6rper sch\u00fctzt sich chronisch und \u00fcbertrieben.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/de\/rape-aroeira\/\"><em><strong>Rap\u00e9 Aroeira<\/strong><\/em><\/a> )<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana.jpg\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana.jpg 800w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana-300x300.jpg 300w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana-150x150.jpg 150w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana-768x768.jpg 768w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana-600x600.jpg 600w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p style=\"text-align: left;\"><strong><a style=\"color: #008000;\" href=\"https:\/\/ancestrina.com\/de\/producto\/rape-imburana\/\">Rap\u00e9 Imburana<\/a> ist das Medikament, das wir empfehlen, um Allergien in allen ihren Erscheinungsformen zu behandeln und zu erforschen.<\/strong> Er bringt die Vorteile von Rap\u00e9 mit, wird Ihnen helfen, sich mit Ihrem Inneren zu verbinden, um diesen Prozess des Erkennens Ihrer Intoleranzen und emotionalen Ablehnungen zu beginnen. <strong>Dar\u00fcber hinaus k\u00f6nnen Sie dank seiner starken Anti-Allergie-Komponenten die k\u00f6rperlichen Symptome Ihrer Allergien behandeln.<\/strong><\/p>\n<p style=\"text-align: center;\"> ( <em><a href=\"https:\/\/ancestrina.com\/de\/rape-cacau\/\"><strong>Rap\u00e9 Cacao<\/strong><\/a><\/em> )<\/p>\n<p style=\"text-align: left;\">Diese Ahnenmedizin geh\u00f6rt zu unserer mittleren Kategorie und ist mit der Arbeit des dritten Chakras oder Solarplexus verbunden. Gleichzeitig <strong>l\u00e4dt es Sie ein, die Ph\u00e4nomene zu erkennen, die Ihre Allergien aktivieren k\u00f6nnen,<\/strong> und Ihre F\u00e4higkeit zu sch\u00e4rfen, all diese Zeichen der Seele lesen zu k\u00f6nnen, um den Weg der Heilung oder Selbstregulierung zu finden, um im Wohlbefinden zu leben.<\/p>\n<p style=\"text-align: center;\"> ( <a href=\"https:\/\/ancestrina.com\/de\/rape-samauma\/\"><em><strong>Rap\u00e9 Samauma<\/strong><\/em><\/a> )<\/p>\n<h3>Wie wird ein ausgeglichenes drittes Chakra projiziert?<br \/>\n<\/h3>\n<ul>\n<li>Sicherheit in uns.<\/li>\n<li>Richtige Grenzen in Ihren Beziehungen.<\/li>\n<li>Motivation.<\/li>\n<li>Willenskraft.<\/li>\n<li>Verbinden und verstehen Sie unsere eigene pers\u00f6nliche Kraft.<\/li>\n<li>F\u00e4higkeit, Entscheidungen zu treffen und keine Angst davor zu haben, sie zu treffen.<\/li>\n<li>Gute Verdauung und ein ausgeglichener Stoffwechsel.<\/li>\n<\/ul>\n<h3>Wie projiziert man ein unausgeglichenes drittes Chakra?<\/h3>\n<ul>\n<li>Energiemangel.<\/li>\n<li>Rebellion und Konkurrenz.<\/li>\n<li>Intoleranz und Reizbarkeit.<\/li>\n<li>Alles kontrollieren wollen.<\/li>\n<li>Mangel an Eigeninitiative.<\/li>\n<li>Geringes Selbstwertgef\u00fchl und Minderwertigkeitskomplex.<\/li>\n<li>Angst, nicht geliebt zu werden oder keinen Partner zu finden.<\/li>\n<li>Verdauungsprobleme<\/li>\n<\/ul>\n<p style=\"text-align: center;\">Wenn Sie mehr \u00fcber Imburana Rap\u00e9 erfahren m\u00f6chten, kontaktieren Sie uns in unseren sozialen Netzwerken als <a style=\"color: #999999;\" href=\"https:\/\/www.instagram.com\/ancestrina\/\"><strong>@ancestrina<\/strong><\/a> , besuchen Sie unseren <a style=\"color: #999999;\" href=\"https:\/\/www.youtube.com\/c\/Ancestrina\"><strong>YouTube-Kanal<\/strong><\/a> oder schreiben Sie uns in die Kommentare, um weitere Informationen \u00fcber den Weg der Medizin zu erhalten. Wir wissen, dass <a style=\"color: #999999;\" href=\"https:\/\/ancestrina.com\/de\/rape-veraendert-leben\/\"><strong>RAP\u00c9 LEBEN VER\u00c4NDERT,<\/strong><\/a> und <strong>wir w\u00fcrden uns freuen, wenn Sie Teil dieser Gemeinschaft w\u00e4ren, die das Bewusstsein durch Medikamente der Vorfahren erweitert.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Wenn dieser Rap\u00e9 Teil Ihrer Reise war, teilen Sie uns bitte Ihre Erfahrungen mit Heilung und Ver\u00e4nderung in den Kommentaren unten mit<\/strong> . Wir glauben an die Geschichten der Transformation, die diese liebevolle Ahnenmedizin gesponnen hat, und wir sind \u00fcberzeugt, dass sie vielen helfen kann, zu ihrer Essenz zur\u00fcckzukehren, in den gegenw\u00e4rtigen Moment zur\u00fcckzukehren und ein Leben voller Wohlbefinden und Sinn zu leben.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Rap\u00e9 Imburana: Alivio Energ\u00e9tico y Emocional para Alergias\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zOCHmUWPN8w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>RAP\u00c9 IMBURANA Zur Behandlung von Allergien Wenn Sie normalerweise an allergischen Erkrankungen wie Asthma, Allergien, Rhinitis, Rosacea oder Ekzemen leiden, hilft es Ihnen nicht nur, Medikamente zu haben, die Ihnen helfen, die Symptome zu lindern &#8230; Aber gehen Sie viel tiefer. Im Allgemeinen haben Allergien aus einem emotionalen und subtilen Bereich mit jenen Elementen oder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[368],"tags":[],"class_list":["post-8404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rape-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RAP\u00c9 IMBURANA , finden Sie heraus, was Sie ablehnen | Ancestrina<\/title>\n<meta name=\"description\" content=\"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/de\/rape-imburana\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RAP\u00c9 IMBURANA\" \/>\n<meta property=\"og:description\" content=\"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/de\/rape-imburana\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-21T16:50:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-04T12:58:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana.jpg\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"RAP\u00c9 IMBURANA\",\"datePublished\":\"2022-01-21T16:50:22+00:00\",\"dateModified\":\"2022-08-04T12:58:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/\"},\"wordCount\":446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"articleSection\":[\"Rap\u00e9\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/\",\"name\":\"RAP\u00c9 IMBURANA , finden Sie heraus, was Sie ablehnen | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"datePublished\":\"2022-01-21T16:50:22+00:00\",\"dateModified\":\"2022-08-04T12:58:05+00:00\",\"description\":\"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-imburana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/zuhause\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAP\u00c9 IMBURANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RAP\u00c9 IMBURANA , finden Sie heraus, was Sie ablehnen | Ancestrina","description":"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/de\/rape-imburana\/","og_locale":"de_DE","og_type":"article","og_title":"RAP\u00c9 IMBURANA","og_description":"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es","og_url":"https:\/\/ancestrina.com\/de\/rape-imburana\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-01-21T16:50:22+00:00","article_modified_time":"2022-08-04T12:58:05+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/12\/imburana.jpg","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Victor Silva","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"RAP\u00c9 IMBURANA","datePublished":"2022-01-21T16:50:22+00:00","dateModified":"2022-08-04T12:58:05+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/"},"wordCount":446,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","articleSection":["Rap\u00e9"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/de\/rape-imburana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/","url":"https:\/\/ancestrina.com\/de\/rape-imburana\/","name":"RAP\u00c9 IMBURANA , finden Sie heraus, was Sie ablehnen | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","datePublished":"2022-01-21T16:50:22+00:00","dateModified":"2022-08-04T12:58:05+00:00","description":"Rap\u00e9 Imburana, um mit Allergien und dem, was sie repr\u00e4sentieren, zu arbeiten, gibt es etwas in Ihrem \u00c4u\u00dferen, das Sie ablehnen, und Ihr K\u00f6rper manifestiert es","breadcrumb":{"@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/de\/rape-imburana\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/de\/rape-imburana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/de\/zuhause\/"},{"@type":"ListItem","position":2,"name":"RAP\u00c9 IMBURANA"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/de\/#website","url":"https:\/\/ancestrina.com\/de\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/de\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/8404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/comments?post=8404"}],"version-history":[{"count":0,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/8404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/media\/35402"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/media?parent=8404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/categories?post=8404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/tags?post=8404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}