{"id":7602,"date":"2021-11-04T11:33:53","date_gmt":"2021-11-04T11:33:53","guid":{"rendered":"http:\/\/ancestrina.com\/schnupftabak-cacto-hilft-du-durch-die-trauerprozesse\/"},"modified":"2022-07-14T16:22:53","modified_gmt":"2022-07-14T16:22:53","slug":"rape-cacto","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/de\/rape-cacto\/","title":{"rendered":"RAP\u00c9 CACTO"},"content":{"rendered":"<h1>RAP\u00c9 CACTO<\/h1>\n<h2>Hilft Ihnen durch den Trauerprozess<\/h2>\n<p style=\"text-align: left;\">Der Tod ist Teil der Erfahrung des Lebendigen. Aus diesem Grund ist <strong>es wichtig, dass Sie Transformation als einen wichtigen Teil Ihrer Lebenserfahrungen einbeziehen k\u00f6nnen.<\/strong> Aber was passiert, wenn Sie Verlusten, Distanz und der Notwendigkeit widerstehen, Aspekte oder Phasen Ihres Lebens zu ver\u00e4ndern? Sie k\u00f6nnen an Emotionen wie Wut, Traurigkeit und Depression haften, damit Sie den Trauerprozess nicht auf gesunde Weise durchleben.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/de\/rape-cielo\/\"><em><strong>Rap\u00e9 Cielo<\/strong><\/em><\/a> )<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto.jpg\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto.jpg 800w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto-300x300.jpg 300w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto-150x150.jpg 150w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto-768x768.jpg 768w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto-600x600.jpg 600w, https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h3>Jawohl&#8230;<\/h3>\n<ul>\n<li>Sie haben materielle Verluste erlitten, die Sie nur schwer verkraften konnten&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; &#8230; &#8230;&#8230;&#8230;..Cacto<\/li>\n<li>Sie haben eine Liebesbeziehung, Freundschaft oder Familie abgeschlossen&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; &#8230;&#8230; &#8230;&#8230;.Cacto<\/li>\n<li>Du stehst vor dem physischen Verlust einer Person, die dir wichtig ist&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..Cacto<\/li>\n<li>Hattest du einen schmerzhaften Streit mit jemandem, den du liebst? &#8230;&#8230;..Cacto<\/li>\n<li>Sie machen einen Umzug oder Gebietswechsel durch, der Ihre St\u00fctzpunkte mobilisiert&#8230;&#8230;&#8230;.Cacto<\/li>\n<li>Sie erkennen, dass Sie einen Lebensabschnitt hinter sich lassen&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; &#8230;&#8230;. &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.Cacto<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Der Kaktus wird Ihnen helfen, den Trauerprozess aus einer gesunden Perspektive zu durchlaufen<\/strong> , indem er verhindert, dass Sie sich an unangenehme Emotionen binden, Ihren Verlust erkennen und dennoch in der Lage sind, nach vorne zu sehen, und Ihnen erm\u00f6glicht, die notwendigen Emotionen zu durchlaufen, um Ihren zu entsprechen trauernde Prozess.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/de\/rape-huasca\/\"><em><strong>Rap\u00e9 Huasca<\/strong><\/em><\/a> )<\/p>\n<p style=\"text-align: left;\">Wie Sie bereits wissen, <strong>wirkt <a href=\"https:\/\/ancestrina.com\/de\/rape-vorteile\/\">Rap\u00e9<\/a> direkt auf unsere Energiezentren<\/strong> oder Chakren. Unser Kaktus erzeugt Gesundheit und subtiles Gleichgewicht auf dem Anahata-Chakra, das auch als Energiezentrum \u00fcber unserem Herzen bekannt ist.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/de\/rape-pixuri\/\"><em><strong>Rap\u00e9 Pixuri<\/strong><\/em><\/a> )<\/p>\n<p style=\"text-align: left;\"><strong><em>Anahata<\/em> ist ein Chakra, das durch das Wasserelement mobilisiert wird und das emotionale Feld unseres K\u00f6rpers und unserer Psyche reinigt<\/strong> . Daher hilft Ihnen dieser Rap\u00e9, Ihren emotionalen K\u00f6rper zu reinigen, um ein Duell, eine Trennung durchzustehen und zu wissen, wie Sie sich in schmerzhaften Momenten begleiten k\u00f6nnen.<\/p>\n<p style=\"text-align: center;\">( <a href=\"https:\/\/ancestrina.com\/de\/was-sind-energiezentren-oder-chakren\/\"><strong>WAS SIND ENERGIEZENTREN ODER CHAKREN?<\/strong><\/a> )<\/p>\n<h3>Wie manifestiert sich ein ausgeglichenes viertes Chakra?<br \/>\n<\/h3>\n<ul>\n<li>Empathie<\/li>\n<li>Mitgef\u00fchl<\/li>\n<li>F\u00e4higkeit zu vergeben<\/li>\n<li>Es gibt keine ungesunden Anhaftungen<\/li>\n<li>Bedingungslos lieben, ohne Vorwand, ohne eine Gegenleistung zu erwarten<\/li>\n<li>Emotionales Gleichgewicht<\/li>\n<li>Sie m\u00f6chten anderen Menschen helfen oder etwas beibringen.<\/li>\n<\/ul>\n<h3>Wie manifestiert sich ein unausgeglichenes viertes Chakra?<\/h3>\n<ul>\n<li>Machen Sie sich die Probleme anderer zu eigen oder machen Sie sich \u00fcberm\u00e4\u00dfig Sorgen.<\/li>\n<li>Legen Sie unsere Bed\u00fcrfnisse beiseite, um sich um andere zu k\u00fcmmern.<\/li>\n<li>Geben ohne zu empfangen.<\/li>\n<li>Empfangen ohne zu geben.<\/li>\n<li>Mangel an Empathie.<\/li>\n<li>Behalten Sie die Kontrolle \u00fcber Ihren Partner.<\/li>\n<li>Irrationale \u00c4ngste<\/li>\n<li>Gef\u00fchl von Einsamkeit, Traurigkeit und Melancholie.<\/li>\n<\/ul>\n<p style=\"text-align: center;\">Wenn Sie mehr \u00fcber Rap\u00e9 Cactus erfahren m\u00f6chten, kontaktieren Sie uns in unseren sozialen Netzwerken als <a style=\"color: #999999;\" href=\"https:\/\/www.instagram.com\/ancestrina\/\"><strong>@ancestrina<\/strong><\/a> , besuchen Sie unseren <a style=\"color: #999999;\" href=\"https:\/\/www.youtube.com\/c\/Ancestrina\"><strong>YouTube-Kanal<\/strong><\/a> oder schreiben Sie uns in die Kommentare, um weitere Informationen \u00fcber den Weg der Medizin zu erhalten. Wir wissen, dass <a style=\"color: #999999;\" href=\"https:\/\/ancestrina.com\/de\/rape-veraendert-leben\/\"><strong>RAP\u00c9 LEBEN VER\u00c4NDERT,<\/strong><\/a> und <strong>wir w\u00fcrden uns freuen, wenn Sie Teil dieser Gemeinschaft w\u00e4ren, die das Bewusstsein durch Medikamente der Vorfahren erweitert.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Wenn dieser Rap\u00e9 Teil Ihrer Reise war, teilen Sie uns bitte Ihre Erfahrungen mit Heilung und Ver\u00e4nderung in den Kommentaren unten mit<\/strong> . Wir glauben an die Geschichten der Transformation, die diese liebevolle Ahnenmedizin gesponnen hat, und wir sind \u00fcberzeugt, dass sie vielen helfen kann, zu ihrer Essenz zur\u00fcckzukehren, in den gegenw\u00e4rtigen Moment zur\u00fcckzukehren und ein Leben voller Wohlbefinden und Sinn zu leben.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Rap\u00e9 Cacto\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dyS3FYb9eG0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>RAP\u00c9 CACTO Hilft Ihnen durch den Trauerprozess Der Tod ist Teil der Erfahrung des Lebendigen. Aus diesem Grund ist es wichtig, dass Sie Transformation als einen wichtigen Teil Ihrer Lebenserfahrungen einbeziehen k\u00f6nnen. Aber was passiert, wenn Sie Verlusten, Distanz und der Notwendigkeit widerstehen, Aspekte oder Phasen Ihres Lebens zu ver\u00e4ndern? Sie k\u00f6nnen an Emotionen wie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[368],"tags":[371,434,436,437,369,438,435],"class_list":["post-7602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rape-de","tag-ahnenmedizin","tag-alte-medikamente","tag-duell","tag-melancholie","tag-schnupftabak","tag-transformation-de","tag-traurigkeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CACTO (kaktus), der Rap\u00e9 , der Ihnen hilft, die Trauerprozesse zu bew\u00e4ltigen<\/title>\n<meta name=\"description\" content=\"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/de\/rape-cacto\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RAP\u00c9 CACTO\" \/>\n<meta property=\"og:description\" content=\"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/de\/rape-cacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-04T11:33:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T16:22:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto.jpg\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"RAP\u00c9 CACTO\",\"datePublished\":\"2021-11-04T11:33:53+00:00\",\"dateModified\":\"2022-07-14T16:22:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"keywords\":[\"Ahnenmedizin\",\"alte Medikamente\",\"Duell\",\"Melancholie\",\"Schnupftabak\",\"Transformation\",\"Traurigkeit\"],\"articleSection\":[\"Rap\u00e9\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/\",\"name\":\"CACTO (kaktus), der Rap\u00e9 , der Ihnen hilft, die Trauerprozesse zu bew\u00e4ltigen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"datePublished\":\"2021-11-04T11:33:53+00:00\",\"dateModified\":\"2022-07-14T16:22:53+00:00\",\"description\":\"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/rape.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/rape-cacto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/zuhause\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAP\u00c9 CACTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CACTO (kaktus), der Rap\u00e9 , der Ihnen hilft, die Trauerprozesse zu bew\u00e4ltigen","description":"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/de\/rape-cacto\/","og_locale":"de_DE","og_type":"article","og_title":"RAP\u00c9 CACTO","og_description":"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.","og_url":"https:\/\/ancestrina.com\/de\/rape-cacto\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2021-11-04T11:33:53+00:00","article_modified_time":"2022-07-14T16:22:53+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2021\/10\/cacto.jpg","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Victor Silva","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"RAP\u00c9 CACTO","datePublished":"2021-11-04T11:33:53+00:00","dateModified":"2022-07-14T16:22:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","keywords":["Ahnenmedizin","alte Medikamente","Duell","Melancholie","Schnupftabak","Transformation","Traurigkeit"],"articleSection":["Rap\u00e9"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/de\/rape-cacto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/","url":"https:\/\/ancestrina.com\/de\/rape-cacto\/","name":"CACTO (kaktus), der Rap\u00e9 , der Ihnen hilft, die Trauerprozesse zu bew\u00e4ltigen","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","datePublished":"2021-11-04T11:33:53+00:00","dateModified":"2022-07-14T16:22:53+00:00","description":"Rap\u00e9 Cacto, Tod ist Teil der Erfahrung des Lebendigen. Lernen Sie, Ihren Trauerprozess zu durchlaufen.","breadcrumb":{"@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/de\/rape-cacto\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/rape.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/de\/rape-cacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/de\/zuhause\/"},{"@type":"ListItem","position":2,"name":"RAP\u00c9 CACTO"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/de\/#website","url":"https:\/\/ancestrina.com\/de\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/de\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/7602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/comments?post=7602"}],"version-history":[{"count":0,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/7602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/media\/35402"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/media?parent=7602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/categories?post=7602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/tags?post=7602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}