{"id":22144,"date":"2022-10-06T17:04:13","date_gmt":"2022-10-06T17:04:13","guid":{"rendered":"http:\/\/ancestrina.com\/was-ist-depression\/"},"modified":"2022-10-26T23:26:52","modified_gmt":"2022-10-26T23:26:52","slug":"was-ist-depression","status":"publish","type":"post","link":"https:\/\/ancestrina.com\/de\/was-ist-depression\/","title":{"rendered":"Was sind Depressionen?"},"content":{"rendered":"<h1>Was sind Depressionen?<\/h1>\n<p>Mit dem Leben gibt es Leiden in Form von Krankheit. Wir glauben, dass es Mikroben, Viren, Bakterien und Verletzungen sind, die Krankheiten in unserem physischen K\u00f6rper verursachen. Ebenso glauben wir, dass es haupts\u00e4chlich ein Ungleichgewicht der Gehirnchemie ist, das geistige und emotionale Krankheiten wie Depressionen, Sucht usw. verursacht.<\/p>\n<p>Im Schamanismus hingegen werden diese Krankheiten und Zust\u00e4nde als Wirkung wahrgenommen. Es wird angenommen, dass man diese Wirkungen oder Symptome f\u00fcr eine echte Heilung nicht einfach mit Medikamenten maskieren und unterdr\u00fccken kann; wir m\u00fcssen die eigentliche Ursache all dieser Probleme angehen. Die Ursache geht weit \u00fcber Viren, Bakterien und Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/de\/was-ist-angst\/\"><em><strong>(WAS IST ANGST?)<\/strong><\/em><\/a><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"246\" src=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp\" alt=\"\" srcset=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp 420w, https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1-300x176.webp 300w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h2>Die 3 Ursachen von Depressionen<\/h2>\n<p>Aus schamanistischer Sicht gibt es 3 klassische Ursachen f\u00fcr Depressionen:<\/p>\n<h3>Disharmonie (oder Machtverlust)<\/h3>\n<p>Disharmonie oder Verlust der pers\u00f6nlichen Kraft treten oft auf, wenn jemand eine wichtige Verbindung zum Leben verloren hat oder wenn das Leben seinen Sinn zu verlieren scheint. Dies kann subtil oder katastrophal geschehen; So oder so erleben wir einen Halt- und Sinnverlust und erleben dabei einen Machtverlust. <\/p>\n<p>Dieser Verlust des Willens oder der Lebenskraft wirkt sich stark und direkt auf unsere Energiematrix aus und kann uns sehr anf\u00e4llig f\u00fcr Krankheiten machen. Ein h\u00e4ufiges, aber tragisches Beispiel daf\u00fcr ist, wenn ein \u00e4lteres Ehepaar den gr\u00f6\u00dften Teil seines Lebens zusammen verbracht hat und einer von ihnen stirbt. Der \u00dcberlebende ger\u00e4t nach dem Verlust oft in eine Lebenskrise, entwickelt bald darauf eine Depression und stirbt dann. Dies ist eine Ursache f\u00fcr Disharmonie aufgrund des Verlustes eines geliebten Menschen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/de\/was-ist-schlaflosigkeit\/\"><em><strong>(WAS IST SCHLAFLOSIGKEIT?)<\/strong><\/em><\/a><\/p>\n<h3>Furcht<\/h3>\n<p>Angst ist die h\u00e4ufigste Ursache f\u00fcr Depressionen. Angst ist verantwortlich f\u00fcr Emotionen, die dazu f\u00fchren, dass Ihr K\u00f6rper in einen Zustand von Stress und dann in Depressionen ger\u00e4t. <\/p>\n<p>Wissenschaftler und Forscher sind sich auch weitgehend einig, dass diese stresserzeugenden Hormone, wenn sie vorhanden sind, schnell beginnen, den Schutzmantel des k\u00f6rpereigenen Immunsystems sowie die gesamte Energiematrix aufzul\u00f6sen. Die Krankheit Depression ist daher unvermeidlich.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/de\/was-sind-krafttiere\/\"><strong><em>(WAS SIND KRAFTIERE?)<\/em><\/strong><\/a><\/p>\n<h3>Seelenverlust<\/h3>\n<p>Seelenverlust ist die extremste, wenn auch leider immer noch h\u00e4ufigste Ursache f\u00fcr Depressionen; Tats\u00e4chlich ist es die schwerwiegendste Diagnose und eine der Hauptursachen f\u00fcr schwere Krankheiten und sogar vorzeitigen Tod.<\/p>\n<p>Seelenverlust wird am h\u00e4ufigsten nach einer traumatischen Erfahrung erlebt, wie z. B. dem Kampf in einem Krieg (ein allzu h\u00e4ufiger Ausl\u00f6ser f\u00fcr PTBS), einer bitteren Scheidung oder intensivem Mobbing. In einigen F\u00e4llen k\u00f6nnen diese Erfahrungen so verheerend sein, dass die eigene Seele zu zersplittern und zu dissoziieren beginnt. In den extremsten und \u00fcberw\u00e4ltigenden F\u00e4llen sind diese Teile der Seele zu verloren und kehren nicht zur\u00fcck.<\/p>\n<p>Wir haben Leute sagen h\u00f6ren wie: \u201eIch bin seit dem Vorfall nicht mehr derselbe\u201c oder \u201eein Teil von mir ist an diesem Tag gestorben\u201c. Diese Kommentare sind Warnzeichen f\u00fcr Seelenverlust.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ancestrina.com\/de\/wofuer-krafttiere-im-schamanismus-verwendet-werden\/\"><em><strong>(WOF\u00dcR WERDEN KRAFTTIERE IM SCHAMANISMUS VERWENDET?)<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was sind Depressionen? Mit dem Leben gibt es Leiden in Form von Krankheit. Wir glauben, dass es Mikroben, Viren, Bakterien und Verletzungen sind, die Krankheiten in unserem physischen K\u00f6rper verursachen. Ebenso glauben wir, dass es haupts\u00e4chlich ein Ungleichgewicht der Gehirnchemie ist, das geistige und emotionale Krankheiten wie Depressionen, Sucht usw. verursacht. Im Schamanismus hingegen werden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[462,453],"tags":[],"class_list":["post-22144","post","type-post","status-publish","format-standard","hentry","category-psychische-gesundheit","category-schlaflosigkeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was sind Depressionen? | Ancestrina<\/title>\n<meta name=\"description\" content=\"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ancestrina.com\/de\/was-ist-depression\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was sind Depressionen?\" \/>\n<meta property=\"og:description\" content=\"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancestrina.com\/de\/was-ist-depression\/\" \/>\n<meta property=\"og:site_name\" content=\"Ancestrina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ancestrina\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T17:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T23:26:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp\" \/>\n<meta name=\"author\" content=\"Victor Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/\"},\"author\":{\"name\":\"Victor Silva\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\"},\"headline\":\"Was sind Depressionen?\",\"datePublished\":\"2022-10-06T17:04:13+00:00\",\"dateModified\":\"2022-10-26T23:26:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"articleSection\":[\"Psychische Gesundheit\",\"Schlaflosigkeit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/\",\"name\":\"Was sind Depressionen? | Ancestrina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"datePublished\":\"2022-10-06T17:04:13+00:00\",\"dateModified\":\"2022-10-26T23:26:52+00:00\",\"description\":\"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/manos-con-agua-brillante-420x246-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/was-ist-depression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/zuhause\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was sind Depressionen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"name\":\"Ancestrina\",\"description\":\"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales\",\"publisher\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#organization\",\"name\":\"Ancestrina\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"contentUrl\":\"https:\\\/\\\/ancestrina.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-ANCESTRINA-1.png\",\"width\":630,\"height\":202,\"caption\":\"Ancestrina\"},\"image\":{\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ancestrina\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ancestrina\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgtt6WFhEIVEI30PzxlOeIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ancestrina.com\\\/de\\\/#\\\/schema\\\/person\\\/70dd45d31d10ed7beb20904b7682c456\",\"name\":\"Victor Silva\",\"sameAs\":[\"https:\\\/\\\/ancestrina.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was sind Depressionen? | Ancestrina","description":"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ancestrina.com\/de\/was-ist-depression\/","og_locale":"de_DE","og_type":"article","og_title":"Was sind Depressionen?","og_description":"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.","og_url":"https:\/\/ancestrina.com\/de\/was-ist-depression\/","og_site_name":"Ancestrina","article_publisher":"https:\/\/www.facebook.com\/Ancestrina\/","article_published_time":"2022-10-06T17:04:13+00:00","article_modified_time":"2022-10-26T23:26:52+00:00","og_image":[{"url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","type":"","width":"","height":""}],"author":"Victor Silva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Victor Silva","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#article","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/"},"author":{"name":"Victor Silva","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456"},"headline":"Was sind Depressionen?","datePublished":"2022-10-06T17:04:13+00:00","dateModified":"2022-10-26T23:26:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"image":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","articleSection":["Psychische Gesundheit","Schlaflosigkeit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ancestrina.com\/de\/was-ist-depression\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/","url":"https:\/\/ancestrina.com\/de\/was-ist-depression\/","name":"Was sind Depressionen? | Ancestrina","isPartOf":{"@id":"https:\/\/ancestrina.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#primaryimage"},"image":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#primaryimage"},"thumbnailUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","datePublished":"2022-10-06T17:04:13+00:00","dateModified":"2022-10-26T23:26:52+00:00","description":"Die eigentliche Ursache von Depressionen geht weit \u00fcber die Gehirnchemie hinaus; Die Hauptursache kommt aus dem inneren Bereich und nicht aus dem Physischen.","breadcrumb":{"@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancestrina.com\/de\/was-ist-depression\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#primaryimage","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2022\/09\/manos-con-agua-brillante-420x246-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/ancestrina.com\/de\/was-ist-depression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancestrina.com\/de\/zuhause\/"},{"@type":"ListItem","position":2,"name":"Was sind Depressionen?"}]},{"@type":"WebSite","@id":"https:\/\/ancestrina.com\/de\/#website","url":"https:\/\/ancestrina.com\/de\/","name":"Ancestrina","description":"Trabajamos experiencias con plantas maestras, terapias integradoras y cultos ancestrales","publisher":{"@id":"https:\/\/ancestrina.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancestrina.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ancestrina.com\/de\/#organization","name":"Ancestrina","url":"https:\/\/ancestrina.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","contentUrl":"https:\/\/ancestrina.com\/wp-content\/uploads\/2020\/06\/cropped-LOGO-ANCESTRINA-1.png","width":630,"height":202,"caption":"Ancestrina"},"image":{"@id":"https:\/\/ancestrina.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ancestrina\/","https:\/\/www.instagram.com\/ancestrina\/","https:\/\/www.youtube.com\/channel\/UCgtt6WFhEIVEI30PzxlOeIw"]},{"@type":"Person","@id":"https:\/\/ancestrina.com\/de\/#\/schema\/person\/70dd45d31d10ed7beb20904b7682c456","name":"Victor Silva","sameAs":["https:\/\/ancestrina.com"]}]}},"_links":{"self":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/22144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/comments?post=22144"}],"version-history":[{"count":2,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/22144\/revisions"}],"predecessor-version":[{"id":22547,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/posts\/22144\/revisions\/22547"}],"wp:attachment":[{"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/media?parent=22144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/categories?post=22144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancestrina.com\/de\/wp-json\/wp\/v2\/tags?post=22144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}